{"id":15267,"date":"2025-03-19T08:26:40","date_gmt":"2025-03-19T08:26:40","guid":{"rendered":"http:\/\/cosmoapart.com\/?page_id=15267"},"modified":"2025-06-19T13:55:37","modified_gmt":"2025-06-19T11:55:37","slug":"cosmo-cookie-policy","status":"publish","type":"page","link":"https:\/\/cosmoapart.com\/it\/cosmo-cookie-policy\/","title":{"rendered":"Informativa sui cookie di Cosmo"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"15267\" class=\"elementor elementor-15267\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-242e478 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"242e478\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe44525\" data-id=\"fe44525\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1119df9 elementor-widget elementor-widget-heading\" data-id=\"1119df9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><br \/>Informativa sui cookie<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9308a4 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c9308a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a81500e elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a81500e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7000962\" data-id=\"7000962\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78775da elementor-widget elementor-widget-text-editor\" data-id=\"78775da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Il portale del Gruppo Cosmopolita, come la maggior parte dei siti web su Internet, utilizza i cookie per migliorare l'esperienza di navigazione dell'utente, analizzare l'utilizzo del sito e migliorare la funzionalit\u00e0 complessiva. I nostri cookie, cos\u00ec come quelli di terze parti che utilizziamo, non riconoscono personalmente alcun utente.<\/span><\/p><p><span style=\"font-weight: 400;\">Questa pagina fornisce informazioni su cosa sono i cookie, su quali cookie utilizziamo e su come potete configurare il loro utilizzo nel vostro browser web.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b8fb71 elementor-widget elementor-widget-heading\" data-id=\"2b8fb71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cosa sono i biscotti?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-260100e elementor-widget elementor-widget-text-editor\" data-id=\"260100e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">I cookie sono piccoli file di testo che vengono memorizzati sul vostro dispositivo quando visitate i siti web. Sono ampiamente utilizzati per far funzionare correttamente o in modo pi\u00f9 efficiente i siti web e per fornire informazioni ai proprietari dei siti web sull'utilizzo del sito.<\/span><\/p><p><span style=\"font-weight: 400;\">Esistono diversi tipi di cookie e vari modi per classificarli:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Gestendo le entit\u00e0<\/b><span style=\"font-weight: 400;\">: Cookie di prima parte (impostati dal sito stesso) e cookie di terze parti (impostati da servizi esterni).<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Per durata<\/b><span style=\"font-weight: 400;\">: Cookie di sessione (cancellati alla chiusura del browser) e cookie persistenti (memorizzati per un periodo pi\u00f9 lungo).<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Per scopo<\/b><span style=\"font-weight: 400;\">: Cookie tecnici, cookie di personalizzazione, cookie di analisi, cookie pubblicitari e cookie di pubblicit\u00e0 comportamentale.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Per maggiori dettagli, \u00e8 possibile consultare la Guida all'uso dei cookie dell'Agenzia spagnola per la protezione dei dati.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d79eca elementor-widget elementor-widget-heading\" data-id=\"5d79eca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quali cookie utilizziamo?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cc00a0 elementor-widget elementor-widget-text-editor\" data-id=\"7cc00a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Di seguito, forniamo una descrizione generale di ciascun tipo e i dettagli dei cookie specifici utilizzati sul nostro sito web.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-273c2a0 elementor-widget elementor-widget-heading\" data-id=\"273c2a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cookie necessari<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7088725 elementor-widget elementor-widget-text-editor\" data-id=\"7088725\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">I cookie necessari contribuiscono a rendere utilizzabile un sito web, consentendo funzioni essenziali come la navigazione e l'accesso ad aree protette. Il sito web non pu\u00f2 funzionare correttamente senza questi cookie.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>PHPSESSID<\/b><span style=\"font-weight: 400;\">: Un identificatore generico usato per mantenere le variabili di sessione dell'utente.<\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Scadenza: Fine sessione.<\/span><\/li><\/ul><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>cb abilitato<\/b><span style=\"font-weight: 400;\">: Memorizza se l'utente ha accettato l'avviso sui cookie.<\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Scadenza: 1 anno.<\/span><\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2b6796 elementor-widget elementor-widget-heading\" data-id=\"e2b6796\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cookie di personalizzazione<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf72feb elementor-widget elementor-widget-text-editor\" data-id=\"cf72feb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Questi cookie consentono al sito web di ricordare informazioni che modificano il comportamento o l'aspetto del sito, come la lingua preferita o le impostazioni regionali.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>lingua<\/b><span style=\"font-weight: 400;\">: Memorizza le preferenze di lingua.<\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Scadenza: 1 anno.<\/span><\/li><\/ul><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>valuta<\/b><span style=\"font-weight: 400;\">: Memorizza la valuta selezionata (ad esempio, EUR).<\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Scadenza: 1 anno.<\/span><\/li><\/ul><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>arrivo_ritorno<\/b><span style=\"font-weight: 400;\">: Memorizza le date di check-in selezionate per le prenotazioni.<\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Scadenza: N\/A.<\/span><\/li><\/ul><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>partenza_ritorno<\/b><span style=\"font-weight: 400;\">: Memorizza le date di check-out selezionate per le prenotazioni.<\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Scadenza: N\/A.<\/span><\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cc138c elementor-widget elementor-widget-heading\" data-id=\"4cc138c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cookie analitici (statistiche web)\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2be9d95 elementor-widget elementor-widget-text-editor\" data-id=\"2be9d95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"font-weight: 400;\" aria-level=\"1\"><p><span style=\"font-weight: 400;\">Questi cookie aiutano i proprietari dei siti web a capire come i visitatori interagiscono con il sito, raccogliendo e fornendo informazioni anonime.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>_ga (Google Analytics)<\/b><span style=\"font-weight: 400;\">: Servizio di analisi web di Google che aiuta a tracciare la navigazione degli utenti.<\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Scadenza: 2 anni.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Disattivare:<\/span><span style=\"color: #fbaf40;\"><a style=\"color: #fbaf40;\" href=\"https:\/\/tools.google.com\/dlpage\/gaoptout\"> <span style=\"font-weight: 400;\">Opt-out di Google Analytics<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/span><\/li><\/ul><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>_dc_gtm_UA-56377430-1 (Google Tag Manager)<\/b><span style=\"font-weight: 400;\">: Utilizzato per caricare altri script e codice.<\/span><ul><li style=\"font-weight: 400;\" aria-level=\"2\"><span style=\"font-weight: 400;\">Scadenza: Non definito.<\/span><\/li><\/ul><\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e14d9d0 elementor-widget elementor-widget-heading\" data-id=\"e14d9d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cookie pubblicitari e di pubblicit\u00e0 comportamentale<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7d40ef elementor-widget elementor-widget-text-editor\" data-id=\"b7d40ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Questi cookie vengono utilizzati per tracciare gli utenti tra i vari siti web al fine di visualizzare annunci pubblicitari pertinenti.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Non utilizziamo cookie pubblicitari.<\/b><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74dabc4 elementor-widget elementor-widget-heading\" data-id=\"74dabc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Altri cookie di terze parti<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ddb66b elementor-widget elementor-widget-text-editor\" data-id=\"9ddb66b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Alcuni cookie di terze parti possono essere installati quando si interagisce con piattaforme esterne (ad esempio, i pulsanti di condivisione dei social media). Questi cookie non provengono dal nostro sito.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Non utilizziamo cookie di terze parti.<\/b><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d904246 elementor-widget elementor-widget-heading\" data-id=\"d904246\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Biscotti non classificati<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-195b3ab elementor-widget elementor-widget-text-editor\" data-id=\"195b3ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Questi cookie sono attualmente in fase di classificazione insieme ai singoli fornitori di cookie.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Non utilizziamo cookie non classificati.<\/b><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f37351 elementor-widget elementor-widget-heading\" data-id=\"4f37351\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Configurazione dell'uso dei cookie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aec6b3f elementor-widget elementor-widget-text-editor\" data-id=\"aec6b3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Questo sito non necessita di cookie per funzionare. Tuttavia, la loro disabilitazione pu\u00f2 influire sull'usabilit\u00e0 di altri siti web. Di seguito, riassumiamo come attivare o disattivare i cookie a seconda del browser utilizzato:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Internet Explorer<\/b><span style=\"font-weight: 400;\">: Vai a <\/span><i><span style=\"font-weight: 400;\">Strumenti<\/span><\/i><span style=\"font-weight: 400;\"> &gt; <\/span><i><span style=\"font-weight: 400;\">Opzioni Internet<\/span><\/i><span style=\"font-weight: 400;\"> &gt; <\/span><i><span style=\"font-weight: 400;\">La privacy<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Firefox<\/b><span style=\"font-weight: 400;\">: Vai a <\/span><i><span style=\"font-weight: 400;\">Strumenti<\/span><\/i><span style=\"font-weight: 400;\"> &gt; <\/span><i><span style=\"font-weight: 400;\">Opzioni<\/span><\/i><span style=\"font-weight: 400;\"> &gt; <\/span><i><span style=\"font-weight: 400;\">La privacy<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Google Chrome\/Android<\/b><span style=\"font-weight: 400;\">: Vai a <\/span><i><span style=\"font-weight: 400;\">Impostazioni<\/span><\/i><span style=\"font-weight: 400;\"> &gt; <\/span><i><span style=\"font-weight: 400;\">Impostazioni avanzate<\/span><\/i><span style=\"font-weight: 400;\"> &gt; <\/span><i><span style=\"font-weight: 400;\">La privacy<\/span><\/i><span style=\"font-weight: 400;\"> &gt; <\/span><i><span style=\"font-weight: 400;\">Impostazioni del contenuto<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Safari (iOS)<\/b><span style=\"font-weight: 400;\">: Vai a <\/span><i><span style=\"font-weight: 400;\">Preferenze<\/span><\/i><span style=\"font-weight: 400;\"> &gt; <\/span><i><span style=\"font-weight: 400;\">La privacy<\/span><\/i><span style=\"font-weight: 400;\"> &gt; <\/span><i><span style=\"font-weight: 400;\">Bloccare i cookie<\/span><\/i><span style=\"font-weight: 400;\">.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17d673e elementor-widget elementor-widget-heading\" data-id=\"17d673e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Accettazione dei cookie\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b53e46 elementor-widget elementor-widget-text-editor\" data-id=\"8b53e46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Continuando a navigare dopo essere stati informati della nostra Politica sui cookie, accettate l'uso dei cookie.<\/span><\/p><p><span style=\"font-weight: 400;\">Quando si accede per la prima volta a questo sito web, viene visualizzata una finestra che informa sull'uso dei cookie e fornisce un link a questa politica. Se si prosegue la navigazione o si clicca su un qualsiasi link, si acconsente all'uso dei cookie.<\/span><\/p><p><span style=\"font-weight: 400;\">Oltre ai nostri cookie, consentiamo a terzi di impostare cookie e di accedervi sul vostro dispositivo. L'accettazione di questi cookie di terze parti \u00e8 legata alla vostra navigazione su questo sito.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2d8227 elementor-widget elementor-widget-heading\" data-id=\"a2d8227\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informativa sulla privacy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6889688 elementor-widget elementor-widget-text-editor\" data-id=\"6889688\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Sebbene non sia direttamente correlato ai cookie, per comodit\u00e0, \u00e8 possibile consultare anche il nostro <\/span><b>Informativa sulla privacy<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d485b03 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d485b03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Cookie Policy The Cosmopolita Group portal, like most websites on the Internet, uses cookies to enhance the user\u2019s browsing experience, analyze website usage, and improve overall functionality. Our cookies, as well as third-party cookies we use, do not personally recognize any user. This page provides information about what cookies are, which cookies we use, and [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-15267","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cosmo Cookie Policy | Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona\u00a0and\u00a0Costa\u00a0Brava<\/title>\n<meta name=\"description\" content=\"Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona\u00a0and\u00a0Costa\u00a0Brava Cookie Policy The Cosmopolita Group portal, like most websites on the Internet, uses cookies to enhance the user\u2019s browsing experience, analyze website\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cosmoapart.com\/it\/wp-json\/wp\/v2\/pages\/15267\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cosmo Cookie Policy\" \/>\n<meta property=\"og:description\" content=\"Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona\u00a0and\u00a0Costa\u00a0Brava Cookie Policy The Cosmopolita Group portal, like most websites on the Internet, uses cookies to enhance the user\u2019s browsing experience, analyze website\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cosmoapart.com\/it\/cosmo-cookie-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona\u00a0and\u00a0Costa\u00a0Brava\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/share\/1Eo3VWZL1L\/?mibextid=wwXIfr\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-19T11:55:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cosmoapart.com\\\/it\\\/cosmo-cookie-policy\\\/\",\"url\":\"https:\\\/\\\/cosmoapart.com\\\/it\\\/cosmo-cookie-policy\\\/\",\"name\":\"Cosmo Cookie Policy | Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona\u00a0and\u00a0Costa\u00a0Brava\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cosmoapart.com\\\/#website\"},\"datePublished\":\"2025-03-19T08:26:40+00:00\",\"dateModified\":\"2025-06-19T11:55:37+00:00\",\"description\":\"Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona\u00a0and\u00a0Costa\u00a0Brava Cookie Policy The Cosmopolita Group portal, like most websites on the Internet, uses cookies to enhance the user\u2019s browsing experience, analyze website\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cosmoapart.com\\\/it\\\/cosmo-cookie-policy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cosmoapart.com\\\/it\\\/cosmo-cookie-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cosmoapart.com\\\/it\\\/cosmo-cookie-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cosmoapart.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cosmo Cookie Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cosmoapart.com\\\/#website\",\"url\":\"https:\\\/\\\/cosmoapart.com\\\/\",\"name\":\"Cosmopolita Group | Luxury Apartments in Barcelona and on Costa Brava\",\"description\":\"Cosmopolita Group presents luxury apartments and a boutique hotel in prime locations of Barcelona and Costa Brava. Enjoy premium comfort, sophisticated design, stunning sea views, and exclusive services, along with special offers and direct booking discounts.\",\"publisher\":{\"@id\":\"https:\\\/\\\/cosmoapart.com\\\/#organization\"},\"alternateName\":\"Cosmopolita Apartments\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cosmoapart.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cosmoapart.com\\\/#organization\",\"name\":\"APARTMENTS COSMOPOLITA, S.L.\",\"alternateName\":\"Cosmopolita Group\",\"url\":\"https:\\\/\\\/cosmoapart.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/cosmoapart.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cosmoapart.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-LogoCosmo-Black-removebg-preview.webp\",\"contentUrl\":\"https:\\\/\\\/cosmoapart.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/cropped-LogoCosmo-Black-removebg-preview.webp\",\"width\":500,\"height\":500,\"caption\":\"APARTMENTS COSMOPOLITA, S.L.\"},\"image\":{\"@id\":\"https:\\\/\\\/cosmoapart.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/share\\\/1Eo3VWZL1L\\\/?mibextid=wwXIfr\",\"https:\\\/\\\/www.instagram.com\\\/cosmo.apartments.elite\\\/\"],\"description\":\"Luxury apartments for rent in Spain, in Barcelona and Cost Brava.\",\"email\":\"info@cosmopolitagroup.com\",\"telephone\":\"+34 933 393 786\",\"legalName\":\"APARTMENTS COSMOPOLITA, S.L.\",\"foundingDate\":\"2016-01-01\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cosmo Cookie Policy | Gruppo Cosmopolita | Appartamenti di lusso e hotel di charme a Barcellona e Costa Brava","description":"Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona and Costa Brava Cookie Policy Il portale Cosmopolita Group, come la maggior parte dei siti web su Internet, utilizza i cookie per migliorare l'esperienza di navigazione dell'utente, analizzare il sito web","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cosmoapart.com\/it\/wp-json\/wp\/v2\/pages\/15267\/","og_locale":"it_IT","og_type":"article","og_title":"Cosmo Cookie Policy","og_description":"Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona\u00a0and\u00a0Costa\u00a0Brava Cookie Policy The Cosmopolita Group portal, like most websites on the Internet, uses cookies to enhance the user\u2019s browsing experience, analyze website","og_url":"https:\/\/cosmoapart.com\/it\/cosmo-cookie-policy\/","og_site_name":"Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona\u00a0and\u00a0Costa\u00a0Brava","article_publisher":"https:\/\/www.facebook.com\/share\/1Eo3VWZL1L\/?mibextid=wwXIfr","article_modified_time":"2025-06-19T11:55:37+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cosmoapart.com\/it\/cosmo-cookie-policy\/","url":"https:\/\/cosmoapart.com\/it\/cosmo-cookie-policy\/","name":"Cosmo Cookie Policy | Gruppo Cosmopolita | Appartamenti di lusso e hotel di charme a Barcellona e Costa Brava","isPartOf":{"@id":"https:\/\/cosmoapart.com\/#website"},"datePublished":"2025-03-19T08:26:40+00:00","dateModified":"2025-06-19T11:55:37+00:00","description":"Cosmopolita Group | Luxury Apartments &amp; Boutique Hotel in Barcelona and Costa Brava Cookie Policy Il portale Cosmopolita Group, come la maggior parte dei siti web su Internet, utilizza i cookie per migliorare l'esperienza di navigazione dell'utente, analizzare il sito web","breadcrumb":{"@id":"https:\/\/cosmoapart.com\/it\/cosmo-cookie-policy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cosmoapart.com\/it\/cosmo-cookie-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cosmoapart.com\/it\/cosmo-cookie-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cosmoapart.com\/"},{"@type":"ListItem","position":2,"name":"Cosmo Cookie Policy"}]},{"@type":"WebSite","@id":"https:\/\/cosmoapart.com\/#website","url":"https:\/\/cosmoapart.com\/","name":"Gruppo Cosmopolita | Appartamenti di lusso a Barcellona e in Costa Brava","description":"Il Gruppo Cosmopolita presenta appartamenti di lusso e un hotel boutique in posizioni privilegiate di Barcellona e della Costa Brava. Godetevi il comfort premium, il design sofisticato, le splendide viste sul mare e i servizi esclusivi, oltre alle offerte speciali e agli sconti per le prenotazioni dirette.","publisher":{"@id":"https:\/\/cosmoapart.com\/#organization"},"alternateName":"Cosmopolita Apartments","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cosmoapart.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cosmoapart.com\/#organization","name":"APPARTAMENTI COSMOPOLITA, S.L.","alternateName":"Cosmopolita Group","url":"https:\/\/cosmoapart.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cosmoapart.com\/#\/schema\/logo\/image\/","url":"https:\/\/cosmoapart.com\/wp-content\/uploads\/2025\/01\/cropped-LogoCosmo-Black-removebg-preview.webp","contentUrl":"https:\/\/cosmoapart.com\/wp-content\/uploads\/2025\/01\/cropped-LogoCosmo-Black-removebg-preview.webp","width":500,"height":500,"caption":"APARTMENTS COSMOPOLITA, S.L."},"image":{"@id":"https:\/\/cosmoapart.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/share\/1Eo3VWZL1L\/?mibextid=wwXIfr","https:\/\/www.instagram.com\/cosmo.apartments.elite\/"],"description":"Appartamenti di lusso in affitto in Spagna, a Barcellona e a Cost Brava.","email":"info@cosmopolitagroup.com","telephone":"+34 933 393 786","legalName":"APARTMENTS COSMOPOLITA, S.L.","foundingDate":"2016-01-01"}]}},"_links":{"self":[{"href":"https:\/\/cosmoapart.com\/it\/wp-json\/wp\/v2\/pages\/15267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cosmoapart.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cosmoapart.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cosmoapart.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cosmoapart.com\/it\/wp-json\/wp\/v2\/comments?post=15267"}],"version-history":[{"count":0,"href":"https:\/\/cosmoapart.com\/it\/wp-json\/wp\/v2\/pages\/15267\/revisions"}],"wp:attachment":[{"href":"https:\/\/cosmoapart.com\/it\/wp-json\/wp\/v2\/media?parent=15267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}